{"id":103549,"date":"2025-03-21T00:10:19","date_gmt":"2025-03-21T00:10:19","guid":{"rendered":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/"},"modified":"2025-03-21T00:10:19","modified_gmt":"2025-03-21T00:10:19","slug":"roblox-introduces-open-source-ai-model-for-3d-objects-msn","status":"publish","type":"post","link":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/","title":{"rendered":"Roblox Introduces Open Source AI Model for 3D Objects &#8211; MSN"},"content":{"rendered":"<p>Roblox has introduced its generative AI model, Cube, enabling creators to design 3D objects through simple text prompts.<br \/><a href=\"https:\/\/www.msn.com\/en-us\/news\/technology\/roblox-introduces-open-source-ai-model-for-3d-objects\/ar-AA1Be0AO\" target=\"_blank\" title=\"Roblox Introduces Open Source AI Model for 3D Objects - MSN\" rel=\"noopener\"> View full source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roblox has introduced its generative AI model, Cube, enabling creators to design 3D objects through [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":1221,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[130],"class_list":["post-103549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-msn"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News<\/title>\n<meta name=\"description\" content=\"Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News\" \/>\n<meta property=\"og:description\" content=\"Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/\" \/>\n<meta property=\"og:site_name\" content=\"Roblox News\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-21T00:10:19+00:00\" \/>\n<meta name=\"author\" content=\"Roblox News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roblox News\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/\"},\"author\":{\"name\":\"Roblox News\",\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/96f9fb85dd23599a909482be8ee303a2\"},\"headline\":\"Roblox Introduces Open Source AI Model for 3D Objects &#8211; MSN\",\"datePublished\":\"2025-03-21T00:10:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/\"},\"wordCount\":32,\"publisher\":{\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/96f9fb85dd23599a909482be8ee303a2\"},\"image\":{\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-359.jpg\",\"keywords\":[\"MSN\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/\",\"url\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/\",\"name\":\"Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-359.jpg\",\"datePublished\":\"2025-03-21T00:10:19+00:00\",\"description\":\"Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-359.jpg\",\"contentUrl\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-359.jpg\",\"width\":2048,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/2025\\\/03\\\/21\\\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roblox Introduces Open Source AI Model for 3D Objects &#8211; MSN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/\",\"name\":\"Roblox News\",\"description\":\"Daily news about Roblox - fresh news, every day\",\"publisher\":{\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/96f9fb85dd23599a909482be8ee303a2\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/roblox.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/96f9fb85dd23599a909482be8ee303a2\",\"name\":\"Roblox News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e79d63087845b681e740cc164cb09039db6d57058929a5f563c53eee5340dce2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e79d63087845b681e740cc164cb09039db6d57058929a5f563c53eee5340dce2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e79d63087845b681e740cc164cb09039db6d57058929a5f563c53eee5340dce2?s=96&d=mm&r=g\",\"caption\":\"Roblox News\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e79d63087845b681e740cc164cb09039db6d57058929a5f563c53eee5340dce2?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/roblox.4800bps.com\\\/blog\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News","description":"Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/","og_locale":"en_US","og_type":"article","og_title":"Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News","og_description":"Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News","og_url":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/","og_site_name":"Roblox News","article_published_time":"2025-03-21T00:10:19+00:00","author":"Roblox News","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Roblox News"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/#article","isPartOf":{"@id":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/"},"author":{"name":"Roblox News","@id":"https:\/\/roblox.4800bps.com\/blog\/#\/schema\/person\/96f9fb85dd23599a909482be8ee303a2"},"headline":"Roblox Introduces Open Source AI Model for 3D Objects &#8211; MSN","datePublished":"2025-03-21T00:10:19+00:00","mainEntityOfPage":{"@id":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/"},"wordCount":32,"publisher":{"@id":"https:\/\/roblox.4800bps.com\/blog\/#\/schema\/person\/96f9fb85dd23599a909482be8ee303a2"},"image":{"@id":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/#primaryimage"},"thumbnailUrl":"https:\/\/roblox.4800bps.com\/blog\/wp-content\/uploads\/temp-359.jpg","keywords":["MSN"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/","url":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/","name":"Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News","isPartOf":{"@id":"https:\/\/roblox.4800bps.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/#primaryimage"},"image":{"@id":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/#primaryimage"},"thumbnailUrl":"https:\/\/roblox.4800bps.com\/blog\/wp-content\/uploads\/temp-359.jpg","datePublished":"2025-03-21T00:10:19+00:00","description":"Roblox Introduces Open Source AI Model for 3D Objects - MSN - Roblox News","breadcrumb":{"@id":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/#primaryimage","url":"https:\/\/roblox.4800bps.com\/blog\/wp-content\/uploads\/temp-359.jpg","contentUrl":"https:\/\/roblox.4800bps.com\/blog\/wp-content\/uploads\/temp-359.jpg","width":2048,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/roblox.4800bps.com\/blog\/2025\/03\/21\/roblox-introduces-open-source-ai-model-for-3d-objects-msn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/roblox.4800bps.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Roblox Introduces Open Source AI Model for 3D Objects &#8211; MSN"}]},{"@type":"WebSite","@id":"https:\/\/roblox.4800bps.com\/blog\/#website","url":"https:\/\/roblox.4800bps.com\/blog\/","name":"Roblox News","description":"Daily news about Roblox - fresh news, every day","publisher":{"@id":"https:\/\/roblox.4800bps.com\/blog\/#\/schema\/person\/96f9fb85dd23599a909482be8ee303a2"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/roblox.4800bps.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/roblox.4800bps.com\/blog\/#\/schema\/person\/96f9fb85dd23599a909482be8ee303a2","name":"Roblox News","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e79d63087845b681e740cc164cb09039db6d57058929a5f563c53eee5340dce2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e79d63087845b681e740cc164cb09039db6d57058929a5f563c53eee5340dce2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e79d63087845b681e740cc164cb09039db6d57058929a5f563c53eee5340dce2?s=96&d=mm&r=g","caption":"Roblox News"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/e79d63087845b681e740cc164cb09039db6d57058929a5f563c53eee5340dce2?s=96&d=mm&r=g"},"sameAs":["http:\/\/roblox.4800bps.com\/blog\/"]}]}},"_links":{"self":[{"href":"https:\/\/roblox.4800bps.com\/blog\/wp-json\/wp\/v2\/posts\/103549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roblox.4800bps.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roblox.4800bps.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roblox.4800bps.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/roblox.4800bps.com\/blog\/wp-json\/wp\/v2\/comments?post=103549"}],"version-history":[{"count":0,"href":"https:\/\/roblox.4800bps.com\/blog\/wp-json\/wp\/v2\/posts\/103549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roblox.4800bps.com\/blog\/wp-json\/wp\/v2\/media\/1221"}],"wp:attachment":[{"href":"https:\/\/roblox.4800bps.com\/blog\/wp-json\/wp\/v2\/media?parent=103549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roblox.4800bps.com\/blog\/wp-json\/wp\/v2\/categories?post=103549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roblox.4800bps.com\/blog\/wp-json\/wp\/v2\/tags?post=103549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}